{"id":72230,"date":"2023-06-30T17:59:50","date_gmt":"2023-06-30T21:59:50","guid":{"rendered":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230"},"modified":"2023-06-30T17:59:50","modified_gmt":"2023-06-30T21:59:50","slug":"fire-breaks-out-at-californias-warner-bros-studios","status":"publish","type":"post","link":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230","title":{"rendered":"Fire breaks out at California&#8217;s Warner Bros. Studios"},"content":{"rendered":"<div>\n<p>A fire broke out Friday at the <a href=\"https:\/\/www.foxnews.com\/entertainment\" target=\"_blank\" rel=\"noopener\">Warner Bros. Studios<\/a> lot in Southern California but no one was injured, the film studio said.\u00a0<\/p>\n<p>The blaze stemmed from a transformer and resulted in an electrical fire, a studio spokesperson told Fox News Digital. An explosion was also heard, according to reports on social media.\u00a0<\/p>\n<p>The <a href=\"https:\/\/www.foxnews.com\/category\/us\/us-regions\/west\/california\" target=\"_blank\" rel=\"noopener\">Glendale and Burbank fire departments<\/a> responded and contained the blaze fairly quickly, the spokesperson said.\u00a0<\/p>\n<p><a href=\"https:\/\/www.foxnews.com\/us\/ex-maryland-police-chief-convicted-setting-revenge-fires-targeting-officials-multiple-life-sentences\" target=\"_blank\" rel=\"noopener\"><strong>EX-MARYLAND POLICE CHIEF CONVICTED OF SETTING &#8216;REVENGE FIRES&#8217; TARGETING OFFICIALS GETS MULTIPLE LIFE SENTENCES<\/strong><\/a><\/p>\n<p>Images posted on social media showed a plume of smoke in the air that appeared off a studio building roof. A single <a href=\"https:\/\/www.foxnews.com\/category\/us\/disasters\/fires\" target=\"_blank\" rel=\"noopener\">fire truck<\/a> was seen pulling into the studio as the dark cloud of smoke billowed in the air, Deadline reported.\u00a0<\/p>\n<p>Fox News Digital has reached out to authorities.\u00a0<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.foxnews.com\/us\/fire-breaks-californias-warner-bros-studios\">Source &#8211; https:\/\/www.foxnews.com\/us\/fire-breaks-californias-warner-bros-studios <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fire broke out Friday at the Warner Bros. Studios lot in Southern California but no one was injured, the film studio said.\u00a0 The blaze [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_2902945987_2902945987":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[16563],"tags":[],"stock_ticker":[],"class_list":["post-72230","post","type-post","status-publish","format-standard","hentry","category-market-news","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fire breaks out at California&#039;s Warner Bros. Studios - Wall Street PR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fire breaks out at California&#039;s Warner Bros. Studios - Wall Street PR\" \/>\n<meta property=\"og:description\" content=\"A fire broke out Friday at the Warner Bros. Studios lot in Southern California but no one was injured, the film studio said.\u00a0 The blaze [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230\" \/>\n<meta property=\"og:site_name\" content=\"Wall Street PR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WallStreetPR\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-30T21:59:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2021\/06\/businessman-showing-business-evolution1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"715\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230#article\",\"isPartOf\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/6e00efa2abc413bdc0bca51a90c54d36\"},\"headline\":\"Fire breaks out at California&#8217;s Warner Bros. Studios\",\"datePublished\":\"2023-06-30T21:59:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230\"},\"wordCount\":149,\"publisher\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#organization\"},\"articleSection\":[\"Market News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230\",\"name\":\"Fire breaks out at California's Warner Bros. Studios - Wall Street PR\",\"isPartOf\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#website\"},\"datePublished\":\"2023-06-30T21:59:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cablemanpro.com\/wallstreetpr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fire breaks out at California&#8217;s Warner Bros. Studios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#website\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/\",\"name\":\"Wall Street PR\",\"description\":\"Latest News From WallStreet\",\"publisher\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cablemanpro.com\/wallstreetpr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#organization\",\"name\":\"Wall Street PR\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2019\/10\/brand-logo.png\",\"contentUrl\":\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2019\/10\/brand-logo.png\",\"width\":537,\"height\":70,\"caption\":\"Wall Street PR\"},\"image\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/WallStreetPR\/\",\"https:\/\/x.com\/WallstreetPRs\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/6e00efa2abc413bdc0bca51a90c54d36\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2022\/09\/360_F_336393115_5gCUfwn76x3MJaCJMYDKLoRebkC8QyrL-300x300.jpg\",\"contentUrl\":\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2022\/09\/360_F_336393115_5gCUfwn76x3MJaCJMYDKLoRebkC8QyrL-300x300.jpg\",\"caption\":\"admin\"},\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fire breaks out at California's Warner Bros. Studios - Wall Street PR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230","og_locale":"en_US","og_type":"article","og_title":"Fire breaks out at California's Warner Bros. Studios - Wall Street PR","og_description":"A fire broke out Friday at the Warner Bros. Studios lot in Southern California but no one was injured, the film studio said.\u00a0 The blaze [&hellip;]","og_url":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230","og_site_name":"Wall Street PR","article_publisher":"https:\/\/www.facebook.com\/WallStreetPR\/","article_published_time":"2023-06-30T21:59:50+00:00","og_image":[{"width":715,"height":423,"url":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2021\/06\/businessman-showing-business-evolution1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230#article","isPartOf":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230"},"author":{"name":"admin","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/6e00efa2abc413bdc0bca51a90c54d36"},"headline":"Fire breaks out at California&#8217;s Warner Bros. Studios","datePublished":"2023-06-30T21:59:50+00:00","mainEntityOfPage":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230"},"wordCount":149,"publisher":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#organization"},"articleSection":["Market News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230","url":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230","name":"Fire breaks out at California's Warner Bros. Studios - Wall Street PR","isPartOf":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#website"},"datePublished":"2023-06-30T21:59:50+00:00","breadcrumb":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/fire-breaks-out-at-californias-warner-bros-studios-72230#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cablemanpro.com\/wallstreetpr\/"},{"@type":"ListItem","position":2,"name":"Fire breaks out at California&#8217;s Warner Bros. Studios"}]},{"@type":"WebSite","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#website","url":"https:\/\/cablemanpro.com\/wallstreetpr\/","name":"Wall Street PR","description":"Latest News From WallStreet","publisher":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cablemanpro.com\/wallstreetpr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#organization","name":"Wall Street PR","url":"https:\/\/cablemanpro.com\/wallstreetpr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/logo\/image\/","url":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2019\/10\/brand-logo.png","contentUrl":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2019\/10\/brand-logo.png","width":537,"height":70,"caption":"Wall Street PR"},"image":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WallStreetPR\/","https:\/\/x.com\/WallstreetPRs"]},{"@type":"Person","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/6e00efa2abc413bdc0bca51a90c54d36","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/image\/","url":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2022\/09\/360_F_336393115_5gCUfwn76x3MJaCJMYDKLoRebkC8QyrL-300x300.jpg","contentUrl":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2022\/09\/360_F_336393115_5gCUfwn76x3MJaCJMYDKLoRebkC8QyrL-300x300.jpg","caption":"admin"},"url":"https:\/\/cablemanpro.com\/wallstreetpr\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/posts\/72230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/comments?post=72230"}],"version-history":[{"count":0,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/posts\/72230\/revisions"}],"wp:attachment":[{"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/media?parent=72230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/categories?post=72230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/tags?post=72230"},{"taxonomy":"stock_ticker","embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/stock_ticker?post=72230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}