{"id":131767,"date":"2026-05-12T21:30:39","date_gmt":"2026-05-13T01:30:39","guid":{"rendered":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767"},"modified":"2026-05-12T21:30:39","modified_gmt":"2026-05-13T01:30:39","slug":"nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor","status":"publish","type":"post","link":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767","title":{"rendered":"Nebraska&#8217;s Pillen wins Republican renomination in bid for second term as governor"},"content":{"rendered":"<div>\n<p>Republican Gov.<a href=\"https:\/\/www.foxnews.com\/person\/p\/jim-pillen\" target=\"_blank\" rel=\"noopener\"> Jim Pillen<\/a> of Nebraska is a big step closer to winning re-election as governor of the red-leaning Great Plains state.<\/p>\n<p>Pillen easily topped five challengers in Nebraska&#8217;s <a href=\"https:\/\/www.foxnews.com\/category\/politics\/elections\/republicans\" target=\"_blank\" rel=\"noopener\">GOP gubernatorial primary<\/a> to win his party&#8217;s 2026 nomination, the Associated Press reports.<\/p>\n<p><a href=\"https:\/\/www.foxnews.com\/elections\" target=\"_blank\" rel=\"noopener\"><strong><u>DEMOCRACY \u201926: STAY UP TO DATE WITH THE FOX NEWS ELECTION HUB<\/u><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.foxnews.com\/category\/politics\/state-and-local\/governors\" target=\"_blank\" rel=\"noopener\">The governor<\/a>, a practicing veterinarian and chair of Pillen Family Farms who also played defensive back for the University of Nebraska Cornhuskers football team five decades ago, was first elected in 2022.<\/p>\n<p>The backing of the outgoing Republican Gov. Pete Ricketts helped Pillen top a crowded field of GOP rivals in the primary before going on to easily win the <a href=\"https:\/\/www.foxnews.com\/category\/politics\/elections\" target=\"_blank\" rel=\"noopener\">general election<\/a>.<\/p>\n<p><a href=\"https:\/\/www.foxnews.com\/politics\/six-months-midterms-senate-seats-could-tip-balance-power\" target=\"_blank\" rel=\"noopener\"><strong><u>SIX MONTHS TILL MIDTERMS: THE TEN RACES THAT WILL DETERMINE THE SENATE&#8217;S MAJORITY<\/u><\/strong><\/a><\/p>\n<p>One week after being sworn in as governor, Pillen appointed Ricketts to fill the <a href=\"https:\/\/www.foxnews.com\/category\/politics\/senate\" target=\"_blank\" rel=\"noopener\">U.S. Senate<\/a> seat left vacant when Republican Sen. Ben Sasse stepped down to become University of Florida president.<\/p>\n<p>Pillen will be considered the clear favorite in the general election in a state President <a href=\"https:\/\/www.foxnews.com\/category\/person\/donald-trump\" target=\"_blank\" rel=\"noopener\">Donald Trump<\/a> carried by 20 points as he won back the White House in 2024.<\/p>\n<p>The governor will face off against former state Sen. Lynne Walz, who won the Democratic nomination, the Associated Press reports.\u00a0<\/p>\n<p>Walz crushed perennial candidate Larry Marvin in the Democratic primary.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.foxnews.com\/politics\/nebraskas-pillen-wins-republican-renomination-bid-second-term-governor\">Source &#8211; https:\/\/www.foxnews.com\/politics\/nebraskas-pillen-wins-republican-renomination-bid-second-term-governor <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Republican Gov. Jim Pillen of Nebraska is a big step closer to winning re-election as governor of the red-leaning Great Plains state. Pillen easily topped [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_2902945987_2902945987":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[16563],"tags":[],"stock_ticker":[],"class_list":["post-131767","post","type-post","status-publish","format-standard","hentry","category-market-news","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nebraska&#039;s Pillen wins Republican renomination in bid for second term as governor - Wall Street PR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nebraska&#039;s Pillen wins Republican renomination in bid for second term as governor - Wall Street PR\" \/>\n<meta property=\"og:description\" content=\"Republican Gov. Jim Pillen of Nebraska is a big step closer to winning re-election as governor of the red-leaning Great Plains state. Pillen easily topped [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767\" \/>\n<meta property=\"og:site_name\" content=\"Wall Street PR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WallStreetPR\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T01:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2021\/06\/businessman-showing-business-evolution1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"715\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767#article\",\"isPartOf\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/6e00efa2abc413bdc0bca51a90c54d36\"},\"headline\":\"Nebraska&#8217;s Pillen wins Republican renomination in bid for second term as governor\",\"datePublished\":\"2026-05-13T01:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767\"},\"wordCount\":237,\"publisher\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#organization\"},\"articleSection\":[\"Market News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767\",\"name\":\"Nebraska's Pillen wins Republican renomination in bid for second term as governor - Wall Street PR\",\"isPartOf\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#website\"},\"datePublished\":\"2026-05-13T01:30:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cablemanpro.com\/wallstreetpr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nebraska&#8217;s Pillen wins Republican renomination in bid for second term as governor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#website\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/\",\"name\":\"Wall Street PR\",\"description\":\"Latest News From WallStreet\",\"publisher\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cablemanpro.com\/wallstreetpr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#organization\",\"name\":\"Wall Street PR\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2019\/10\/brand-logo.png\",\"contentUrl\":\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2019\/10\/brand-logo.png\",\"width\":537,\"height\":70,\"caption\":\"Wall Street PR\"},\"image\":{\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/WallStreetPR\/\",\"https:\/\/x.com\/WallstreetPRs\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/6e00efa2abc413bdc0bca51a90c54d36\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2022\/09\/360_F_336393115_5gCUfwn76x3MJaCJMYDKLoRebkC8QyrL-300x300.jpg\",\"contentUrl\":\"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2022\/09\/360_F_336393115_5gCUfwn76x3MJaCJMYDKLoRebkC8QyrL-300x300.jpg\",\"caption\":\"admin\"},\"url\":\"https:\/\/cablemanpro.com\/wallstreetpr\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nebraska's Pillen wins Republican renomination in bid for second term as governor - Wall Street PR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767","og_locale":"en_US","og_type":"article","og_title":"Nebraska's Pillen wins Republican renomination in bid for second term as governor - Wall Street PR","og_description":"Republican Gov. Jim Pillen of Nebraska is a big step closer to winning re-election as governor of the red-leaning Great Plains state. Pillen easily topped [&hellip;]","og_url":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767","og_site_name":"Wall Street PR","article_publisher":"https:\/\/www.facebook.com\/WallStreetPR\/","article_published_time":"2026-05-13T01:30:39+00:00","og_image":[{"width":715,"height":423,"url":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2021\/06\/businessman-showing-business-evolution1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767#article","isPartOf":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767"},"author":{"name":"admin","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/6e00efa2abc413bdc0bca51a90c54d36"},"headline":"Nebraska&#8217;s Pillen wins Republican renomination in bid for second term as governor","datePublished":"2026-05-13T01:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767"},"wordCount":237,"publisher":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#organization"},"articleSection":["Market News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767","url":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767","name":"Nebraska's Pillen wins Republican renomination in bid for second term as governor - Wall Street PR","isPartOf":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#website"},"datePublished":"2026-05-13T01:30:39+00:00","breadcrumb":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/nebraskas-pillen-wins-republican-renomination-in-bid-for-second-term-as-governor-131767#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cablemanpro.com\/wallstreetpr\/"},{"@type":"ListItem","position":2,"name":"Nebraska&#8217;s Pillen wins Republican renomination in bid for second term as governor"}]},{"@type":"WebSite","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#website","url":"https:\/\/cablemanpro.com\/wallstreetpr\/","name":"Wall Street PR","description":"Latest News From WallStreet","publisher":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cablemanpro.com\/wallstreetpr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#organization","name":"Wall Street PR","url":"https:\/\/cablemanpro.com\/wallstreetpr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/logo\/image\/","url":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2019\/10\/brand-logo.png","contentUrl":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2019\/10\/brand-logo.png","width":537,"height":70,"caption":"Wall Street PR"},"image":{"@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WallStreetPR\/","https:\/\/x.com\/WallstreetPRs"]},{"@type":"Person","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/6e00efa2abc413bdc0bca51a90c54d36","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cablemanpro.com\/wallstreetpr\/#\/schema\/person\/image\/","url":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2022\/09\/360_F_336393115_5gCUfwn76x3MJaCJMYDKLoRebkC8QyrL-300x300.jpg","contentUrl":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-content\/uploads\/2022\/09\/360_F_336393115_5gCUfwn76x3MJaCJMYDKLoRebkC8QyrL-300x300.jpg","caption":"admin"},"url":"https:\/\/cablemanpro.com\/wallstreetpr\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/posts\/131767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/comments?post=131767"}],"version-history":[{"count":0,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/posts\/131767\/revisions"}],"wp:attachment":[{"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/media?parent=131767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/categories?post=131767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/tags?post=131767"},{"taxonomy":"stock_ticker","embeddable":true,"href":"https:\/\/cablemanpro.com\/wallstreetpr\/wp-json\/wp\/v2\/stock_ticker?post=131767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}